{"id":782,"date":"2024-08-15T20:38:07","date_gmt":"2024-08-15T20:38:07","guid":{"rendered":"https:\/\/participa.chihuahua.gob.mx\/?p=782"},"modified":"2025-03-06T19:11:12","modified_gmt":"2025-03-06T19:11:12","slug":"participa","status":"publish","type":"post","link":"https:\/\/participa.chihuahua.gob.mx\/index.php\/2024\/08\/15\/participa\/","title":{"rendered":"Participa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es?<\/h2>\n\n\n\n<p>Es una herramienta digital por medio de la cual las Dependencias y Entidades de la APF, impulsan, promueven e implementan&nbsp;<strong>mecanismos de participaci\u00f3n ciudadana en la prevenci\u00f3n y el combate a la corrupci\u00f3n<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1201\" height=\"1200\" src=\"https:\/\/participa.chihuahua.gob.mx\/wp-content\/uploads\/2025\/03\/infos-Participa-2024-abril-01.jpg\" alt=\"\" class=\"wp-image-983\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1702\" height=\"2552\" src=\"https:\/\/participa.chihuahua.gob.mx\/wp-content\/uploads\/2024\/08\/Poster-Participa-2024-MARZO-01-002.jpg\" alt=\"\" class=\"wp-image-783\"\/><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><a href=\"https:\/\/participa.gob.mx\/\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 promueve?<\/strong><\/h2>\n\n\n\n<p>El&nbsp;<strong>fortalecimiento de la relaci\u00f3n Sociedad-Gobierno&nbsp;<\/strong>a trav\u00e9s de un espacio de inclusi\u00f3n e involucramiento de la ciudadan\u00eda que contribuya a la toma de decisiones de manera efectiva, inclusiva y colaborativa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1536\" height=\"681\" src=\"https:\/\/participa.chihuahua.gob.mx\/wp-content\/uploads\/2024\/08\/imagen.png\" alt=\"\" class=\"wp-image-784\"\/><\/figure>\n\n\n\n<div class=\"wp-block-buttons alignwide is-content-justification-center is-layout-flex wp-container-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\">Participa<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es? Es una herramienta digital por medio de la cual las Dependencias y Entidades de la APF, impulsan, promueven e implementan&nbsp;mecanismos de participaci\u00f3n ciudadana en la prevenci\u00f3n y el combate a la corrupci\u00f3n. \u00bfQu\u00e9 promueve? El&nbsp;fortalecimiento de la relaci\u00f3n Sociedad-Gobierno&nbsp;a trav\u00e9s de un espacio de inclusi\u00f3n e involucramiento de la ciudadan\u00eda que contribuya a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/participa.chihuahua.gob.mx\/index.php\/2024\/08\/15\/participa\/\" class=\"more-link\">Leer m\u00e1s<span class=\"screen-reader-text\"> \u00abParticipa\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/782"}],"collection":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":3,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions\/984"}],"wp:attachment":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}