{"id":1158,"date":"2026-02-16T19:47:22","date_gmt":"2026-02-16T19:47:22","guid":{"rendered":"https:\/\/participa.chihuahua.gob.mx\/?p=1158"},"modified":"2026-05-12T21:03:02","modified_gmt":"2026-05-12T21:03:02","slug":"respalda-sfp-posicionamiento-institucional-en-defensa-del-estado-de-derecho","status":"publish","type":"post","link":"https:\/\/participa.chihuahua.gob.mx\/index.php\/2026\/02\/16\/respalda-sfp-posicionamiento-institucional-en-defensa-del-estado-de-derecho\/","title":{"rendered":"Respalda SFP posicionamiento institucional en defensa del Estado de Derecho"},"content":{"rendered":"\n<p>La Secretar\u00eda de la Funci\u00f3n P\u00fablica (SFP), en su car\u00e1cter de representante del Poder Ejecutivo del Estado e integrante del Sistema Estatal Anticorrupci\u00f3n, respald\u00f3 el posicionamiento institucional emitido en el marco de la Primera Sesi\u00f3n Extraordinaria del Comit\u00e9 Coordinador del Sistema Estatal Anticorrupci\u00f3n.<\/p>\n\n\n\n<p>Esto relativo a la resoluci\u00f3n del Primer Tribunal Colegiado en Materia Penal y Administrativa del D\u00e9cimo S\u00e9ptimo Circuito dentro del Conflicto Competencial 20\/2025.<\/p>\n\n\n\n<p>Durante su intervenci\u00f3n, el titular de la SFP, Roberto Javier Fierro, manifest\u00f3 que resulta lamentable cualquier actuaci\u00f3n que vulnere el adecuado ejercicio institucional, particularmente cuando se trata de instancias que forman parte del Sistema Nacional de Fiscalizaci\u00f3n.<\/p>\n\n\n\n<p>El secretario subray\u00f3 que es inadmisible que, bajo argumentos de atracci\u00f3n o competencia, se pretenda reclasificar o modificar el curso de carpetas de investigaci\u00f3n con el prop\u00f3sito de favorecer intereses particulares.<\/p>\n\n\n\n<p>Adem\u00e1s se\u00f1al\u00f3 que el Gobierno Federal tiene la responsabilidad irrenunciable de resguardar el Estado de Derecho, garantizar la legalidad y salvaguardar la autonom\u00eda de las instituciones encargadas de la procuraci\u00f3n y administraci\u00f3n de justicia.<\/p>\n\n\n\n<p>La Secretar\u00eda de la Funci\u00f3n P\u00fablica refrenda su compromiso con la transparencia, la rendici\u00f3n de cuentas y el combate frontal a la corrupci\u00f3n, as\u00ed como con el fortalecimiento del Sistema Estatal Anticorrupci\u00f3n como un mecanismo fundamental para garantizar la integridad en el servicio p\u00fablico.<\/p>\n\n\n\n<p>El Poder Ejecutivo del Estado, a trav\u00e9s de la SFP, actuar\u00e1 con firmeza, apego a la ley y respeto a las resoluciones judiciales, siempre en defensa de la institucionalidad y del inter\u00e9s p\u00fablico.<\/p>\n\n\n\n<p>Tomado de: Micrositio SFP<br>En: <a href=\"https:\/\/www.chihuahua.gob.mx\/index.php\/prensa\/respalda-sfp-posicionamiento-institucional-en-defensa-del-estado-de-derecho\">https:\/\/www.chihuahua.gob.mx\/index.php\/prensa\/respalda-sfp-posicionamiento-institucional-en-defensa-del-estado-de-derecho<\/a><br>Fecha de publicaci\u00f3n original: 09\/10\/2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de la Funci\u00f3n P\u00fablica (SFP), en su car\u00e1cter de representante del Poder Ejecutivo del Estado e integrante del Sistema Estatal Anticorrupci\u00f3n, respald\u00f3 el posicionamiento institucional emitido en el marco de la Primera Sesi\u00f3n Extraordinaria del Comit\u00e9 Coordinador del Sistema Estatal Anticorrupci\u00f3n. Esto relativo a la resoluci\u00f3n del Primer Tribunal Colegiado en Materia Penal &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/participa.chihuahua.gob.mx\/index.php\/2026\/02\/16\/respalda-sfp-posicionamiento-institucional-en-defensa-del-estado-de-derecho\/\" class=\"more-link\">Leer m\u00e1s<span class=\"screen-reader-text\"> \u00abRespalda SFP posicionamiento institucional en defensa del Estado de Derecho\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"_links":{"self":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/1158"}],"collection":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1158"}],"version-history":[{"count":2,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/1158\/revisions"}],"predecessor-version":[{"id":1169,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/posts\/1158\/revisions\/1169"}],"wp:attachment":[{"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/participa.chihuahua.gob.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}